{"id":21791,"date":"2026-01-15T15:03:16","date_gmt":"2026-01-15T20:03:16","guid":{"rendered":"https:\/\/margill.com\/?post_type=ufaq&#038;p=21791"},"modified":"2026-01-15T15:03:19","modified_gmt":"2026-01-15T20:03:19","slug":"comment-sont-estimes-les-delais-et-les-couts","status":"publish","type":"ufaq","link":"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/","title":{"rendered":"Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ?"},"content":{"rendered":"<div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-distinct ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='title' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/fr\/wp-json\/wp\/v2\/ufaq\/21791' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-default ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-21791-b3qhC4DgC7' data-post_id='21791'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h3>\n\t\t\t\tComment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ?\t\t\t<\/h3>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t\n<p class=\"wp-block-paragraph\">Les d\u00e9lais et les co\u00fbts sont \u00e9valu\u00e9s apr\u00e8s l\u2019analyse initiale des besoins. Une estimation est fournie avant le d\u00e9but du d\u00e9veloppement, en fonction de la complexit\u00e9 du mandat et des fonctionnalit\u00e9s \u00e0 livrer.<\/p>\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? Les d\u00e9lais et les co\u00fbts sont \u00e9valu\u00e9s apr\u00e8s l\u2019analyse initiale des besoins. Une estimation est fournie avant le d\u00e9but du d\u00e9veloppement, en fonction de la complexit\u00e9 du mandat et des fonctionnalit\u00e9s \u00e0 livrer.<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","ufaq-category":[439],"ufaq-tag":[],"class_list":["post-21791","ufaq","type-ufaq","status-publish","hentry","ufaq-category-services-de-developpement-sur-mesure-pour-la-gestion-de-prets"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? - Margill<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? - Margill\" \/>\r\n<meta property=\"og:description\" content=\"A Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? Les d\u00e9lais et les co\u00fbts sont \u00e9valu\u00e9s apr\u00e8s l\u2019analyse initiale des besoins. Une estimation est fournie avant le d\u00e9but du d\u00e9veloppement, en fonction de la complexit\u00e9 du mandat et des fonctionnalit\u00e9s \u00e0 livrer.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Margill\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-01-15T20:03:19+00:00\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/margill.com\\\/fr\\\/ufaq\\\/comment-sont-estimes-les-delais-et-les-couts\\\/\",\"url\":\"https:\\\/\\\/margill.com\\\/fr\\\/ufaq\\\/comment-sont-estimes-les-delais-et-les-couts\\\/\",\"name\":\"Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? - Margill\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/margill.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-01-15T20:03:16+00:00\",\"dateModified\":\"2026-01-15T20:03:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/margill.com\\\/fr\\\/ufaq\\\/comment-sont-estimes-les-delais-et-les-couts\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/margill.com\\\/fr\\\/ufaq\\\/comment-sont-estimes-les-delais-et-les-couts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/margill.com\\\/fr\\\/ufaq\\\/comment-sont-estimes-les-delais-et-les-couts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/margill.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/margill.com\\\/fr\\\/ufaq\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/margill.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/margill.com\\\/fr\\\/\",\"name\":\"Margill\",\"description\":\"Loan Servicing Solutions \\\/ Interest Calculators\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/margill.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? - Margill","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? - Margill","og_description":"A Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? Les d\u00e9lais et les co\u00fbts sont \u00e9valu\u00e9s apr\u00e8s l\u2019analyse initiale des besoins. Une estimation est fournie avant le d\u00e9but du d\u00e9veloppement, en fonction de la complexit\u00e9 du mandat et des fonctionnalit\u00e9s \u00e0 livrer.","og_url":"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/","og_site_name":"Margill","article_modified_time":"2026-01-15T20:03:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/","url":"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/","name":"Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ? - Margill","isPartOf":{"@id":"https:\/\/margill.com\/fr\/#website"},"datePublished":"2026-01-15T20:03:16+00:00","dateModified":"2026-01-15T20:03:19+00:00","breadcrumb":{"@id":"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/margill.com\/fr\/ufaq\/comment-sont-estimes-les-delais-et-les-couts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/margill.com\/fr\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/margill.com\/fr\/ufaq\/"},{"@type":"ListItem","position":3,"name":"Comment sont estim\u00e9s les d\u00e9lais et les co\u00fbts ?"}]},{"@type":"WebSite","@id":"https:\/\/margill.com\/fr\/#website","url":"https:\/\/margill.com\/fr\/","name":"Margill","description":"Loan Servicing Solutions \/ Interest Calculators","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/margill.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/margill.com\/fr\/wp-json\/wp\/v2\/ufaq\/21791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/margill.com\/fr\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/margill.com\/fr\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/margill.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/margill.com\/fr\/wp-json\/wp\/v2\/comments?post=21791"}],"wp:attachment":[{"href":"https:\/\/margill.com\/fr\/wp-json\/wp\/v2\/media?parent=21791"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/margill.com\/fr\/wp-json\/wp\/v2\/ufaq-category?post=21791"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/margill.com\/fr\/wp-json\/wp\/v2\/ufaq-tag?post=21791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}